{"id":2275,"date":"2023-07-26T10:02:31","date_gmt":"2023-07-26T13:02:31","guid":{"rendered":"https:\/\/www.clayss.org\/?page_id=2275"},"modified":"2025-06-19T12:24:49","modified_gmt":"2025-06-19T15:24:49","slug":"networks","status":"publish","type":"page","link":"https:\/\/www.clayss.org\/en\/networks\/","title":{"rendered":"Networks"},"content":{"rendered":"<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-2144704441\">\n\n\t<div id=\"col-234267819\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(248, 177, 51);\" >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1154330321\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1270\" height=\"500\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/redibas.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1154330321 {\n  padding-top: 51%;\n  background-color: rgb(248, 177, 51);\n}\n@media (min-width:550px) {\n  #banner-1154330321 {\n    padding-top: 530px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-205747392\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(248, 177, 51);\" >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-1825981239\">\n\n\n\t<div id=\"col-170254581\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(248, 177, 51);\" >\n\t\t\t\n\t\t\t\n\n<h2>Networks and Partners<br \/>\n<\/h2>\n\t<div id=\"gap-1063974323\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1063974323 {\n  padding-top: 10%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"ux-menu stack stack-col justify-start ux-menu--divider-solid\">\n\t\t\n\n\t<div class=\"ux-menu-link flex menu-item menuflecha\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.clayss.org\/en\/redes-y-alianzas\/#redibas\" >\n\t\t\t<i class=\"ux-menu-link__icon text-center icon-angle-right\" aria-hidden=\"true\"><\/i>\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tIbero-American Service-Learning Network\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\n\t<div class=\"ux-menu-link flex menu-item menuflecha\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.clayss.org\/en\/redes-y-alianzas\/#redes-internacionales\" >\n\t\t\t<i class=\"ux-menu-link__icon text-center icon-angle-right\" aria-hidden=\"true\"><\/i>\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tInternational Networks\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\n\t<div class=\"ux-menu-link flex menu-item menuflecha\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.clayss.org\/en\/redes\/#redes-regionales\" >\n\t\t\t<i class=\"ux-menu-link__icon text-center icon-angle-right\" aria-hidden=\"true\"><\/i>\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tRegional Networks\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\n\t<div class=\"ux-menu-link flex menu-item menuflecha\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.clayss.org\/en\/redes\/#redes-regionales\" >\n\t\t\t<i class=\"ux-menu-link__icon text-center icon-angle-right\" aria-hidden=\"true\"><\/i>\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tNational Networks\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\n\t<div class=\"ux-menu-link flex menu-item menuflecha\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.clayss.org\/en\/redes\/#organizaciones\" >\n\t\t\t<i class=\"ux-menu-link__icon text-center icon-angle-right\" aria-hidden=\"true\"><\/i>\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tPartner Organizations\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\n\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-170254581 > .col-inner {\n  padding: 30px 30px 30px 30px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1825981239 > .col > .col-inner {\n  background-color: rgb(248, 177, 51);\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_715181384\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-equal\"  id=\"row-1902028928\">\n\n\t<div id=\"col-485589053\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3340273483\" class=\"text titulo\">\n\t\t\n<p style=\"margin: 0;\"><span style=\"font-family: 'Montserrat'; margin: 0;\">Networks and Partners<br \/>\n<\/span><\/p>\n\t\t\n<style>\n#text-3340273483 {\n  font-size: 1.5rem;\n  line-height: 1.25;\n  text-align: center;\n  color: rgb(189, 22, 34);\n}\n#text-3340273483 > * {\n  color: rgb(189, 22, 34);\n}\n@media (min-width:550px) {\n  #text-3340273483 {\n    font-size: 1.95rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:10px;margin-bottom:10px;max-width:100%;background-color:rgb(167, 51, 54);\"><\/div>\n<p dir=\"ltr\"><strong>In CLAYSS, we believe that diversity and community work is the best way to implement service-learning, participating in the complex world and transforming reality.<\/strong><\/p>\n<p dir=\"ltr\">Thanks to joint work, getting to know each other and ourselves enhances our work and increases its result.<\/p>\n<p dir=\"ltr\">That is why we support the creation of more national and regional service-learning networks and are also part of networks that promote it worldwide.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_715181384 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1565958059\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-equal\"  id=\"row-788544089\">\n\n\t<div id=\"col-963198083\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #redes-regionales\" data-bullet=\"false\" data-link=\"#redes-regionales\" data-title=\"redes regionales\"><a name=\"redes-regionales\"><\/a><\/span>\n\t<div id=\"text-3723070851\" class=\"text titulo\">\n\t\t\n<p style=\"margin: 0;\"><span style=\"font-family: 'Montserrat'; margin: 0;\">Regional Networks<\/span><\/p>\n\t\t\n<style>\n#text-3723070851 {\n  font-size: 1.5rem;\n  line-height: 1.25;\n  text-align: center;\n  color: rgb(189, 22, 34);\n}\n#text-3723070851 > * {\n  color: rgb(189, 22, 34);\n}\n@media (min-width:550px) {\n  #text-3723070851 {\n    font-size: 1.95rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:10px;margin-bottom:10px;max-width:100%;background-color:rgb(167, 51, 54);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-150070543\">\n\n\t<div id=\"col-715552118\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>In this map you will find the <strong>Regional Networks<\/strong> (marked as <strong>RR<\/strong>) and <strong>National Networks<\/strong> (marked as <strong>RN<\/strong>).<\/p>\n<p>To know the National Networks that integrate the <strong>Ibero-American Network of Service-Learning (RedIBAS)<\/strong>\u00a0and the <strong>Pan-European Network of Service-Learning in Schools and Organizations<\/strong>, click on the map and the side menu with the members of each one will be displayed.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1565958059 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-430247807\">\n\n\t<div id=\"col-1455050396\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/maphub.net\/embed_h\/hKnUSMJ3Tt03bj07?panel=1\" width=\"100%\" height=\"576\" frameborder=\"0\" data-mce-fragment=\"1\"><\/iframe><br \/>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<span class=\"scroll-to\" data-label=\"Scroll to: #redibas\" data-bullet=\"false\" data-link=\"#redibas\" data-title=\"REDIBAS\"><a name=\"redibas\"><\/a><\/span>\n\n  <div class=\"banner has-hover\" id=\"banner-2057566295\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1918\" height=\"628\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/07\/banner-redes-2-02.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/redes\/red-iberoamericana-aprendizaje-servicio\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-205388494\" class=\"text-box banner-layer x50 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1856278363\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"441\" height=\"230\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2025\/06\/red-iberoamericana_20.png\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1856278363 {\n  width: 55%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1229847698\" class=\"text\">\n\t\t\n<p>The Ibero-American Network of Service-Learning (REDIBAS) was founded in Buenos Aires on October 29, 2005 by a group of government agencies, civil society organizations, universities and regional organizations from Latin America, the United States and Spain that shared an interest in promoting service-learning as a pedagogical proposal, for citizen and social protagonism of children, adolescents and young people, and as a tool for the transformation of reality.<\/p>\n\t\t\n<style>\n#text-1229847698 {\n  font-size: 0.75rem;\n  line-height: 1.35;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.clayss.org\/en\/networks\/the-ibero-american-service-learning-network-redibas\/\" class=\"button secondary\" >\n\t\t<span>View more<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-205388494 {\n  width: 90%;\n}\n#text-box-205388494 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-205388494 {\n    width: 43%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2057566295 {\n  padding-top: 113%;\n  background-color: rgb(255,255,255);\n}\n#banner-2057566295 .banner-bg img {\n  object-position: right;\n}\n@media (min-width:550px) {\n  #banner-2057566295 {\n    padding-top: 37%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1727434141\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-equal align-center\"  id=\"row-1024779710\">\n\n\t<div id=\"col-865134447\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #redes-internacionales\" data-bullet=\"false\" data-link=\"#redes-internacionales\" data-title=\"Redes Internacionales\"><a name=\"redes-internacionales\"><\/a><\/span>\n\t<div id=\"text-3851856929\" class=\"text titulo\">\n\t\t\n<p style=\"margin: 0;\">Global Networks<\/p>\n\t\t\n<style>\n#text-3851856929 {\n  font-size: 1.5rem;\n  line-height: 1.25;\n  text-align: center;\n  color: rgb(189, 22, 34);\n}\n#text-3851856929 > * {\n  color: rgb(189, 22, 34);\n}\n@media (min-width:550px) {\n  #text-3851856929 {\n    font-size: 1.95rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:10px;margin-bottom:10px;max-width:100%;background-color:rgb(189, 22, 34);\"><\/div>\n\t<div id=\"gap-1647617044\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1647617044 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-865134447 > .col-inner {\n  margin: 0px 0px -67px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1024779710 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-1217080811\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1217080811 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1768100459\">\n\n\t<div id=\"col-570843054\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-75694093\" >\n    <div class=\"slider slider-nav-simple slider-nav-normal slider-nav-dark slider-nav-outside slider-style-container slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"left\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": true,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/catalyst2030.net\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2025\/01\/catalys-1.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 274.4776119403px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.iarslce.org\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/06\/iarslce-04-04.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/scholasoccurrentes.org\/es\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/07\/scholas.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 274.4776119403px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/talloiresnetwork.tufts.edu\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/06\/talloires-04-04.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/community-arts.net\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/07\/communityArts.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.uniservitate.org\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/07\/uniservitate.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1727434141 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1694652130\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-equal align-center\"  id=\"row-656604703\">\n\n\t<div id=\"col-2095815817\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-921364529\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-921364529 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #organizaciones\" data-bullet=\"false\" data-link=\"#organizaciones\" data-title=\"Organizaciones\"><a name=\"organizaciones\"><\/a><\/span>\n\t<div id=\"text-1602505926\" class=\"text titulo\">\n\t\t\n<p style=\"margin: 0;\">Partner Organizations<\/p>\n\t\t\n<style>\n#text-1602505926 {\n  font-size: 1.5rem;\n  line-height: 1.25;\n  text-align: center;\n  color: rgb(189, 22, 34);\n}\n#text-1602505926 > * {\n  color: rgb(189, 22, 34);\n}\n@media (min-width:550px) {\n  #text-1602505926 {\n    font-size: 1.95rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:10px;margin-bottom:10px;max-width:100%;background-color:rgb(189, 22, 34);\"><\/div>\n\t<div id=\"gap-283949522\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-283949522 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2095815817 > .col-inner {\n  margin: 0px 0px -67px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-656604703 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-1962726242\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1962726242 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-2054078554\">\n\n\t<div id=\"col-934117381\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1379878144\" >\n    <div class=\"slider slider-nav-simple slider-nav-normal slider-nav-dark slider-nav-outside slider-style-container slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"left\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": true,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"Fundaci\u00f3n Am\u00e9rica Solidaria\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/americasolidaria.org\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/america_solidaria.png\" title=\"Fundaci\u00f3n Am\u00e9rica Solidaria\" alt=\"Fundaci\u00f3n Am\u00e9rica Solidaria\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"Ashoka Cono Sur\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ashoka.org\/es-ar\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/ashoka.png\" title=\"Ashoka Cono Sur\" alt=\"Ashoka Cono Sur\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><div class=\"ux-logo-link block image-\" title=\"GYSD\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/gysd.png\" title=\"GYSD\" alt=\"GYSD\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><div class=\"ux-logo-link block image-\" title=\"IANYS\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/ianys.png\" title=\"IANYS\" alt=\"IANYS\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"International Baccalaureate Organization\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ibo.org\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/ib.png\" title=\"International Baccalaureate Organization\" alt=\"International Baccalaureate Organization\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"Peace Corps\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.peacecorps.gov\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/peacecorps.png\" title=\"Peace Corps\" alt=\"Peace Corps\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"RACI\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/raci.org.ar\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/raci.png\" title=\"RACI\" alt=\"RACI\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"Fundaci\u00f3n Varkey\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.fundacionvarkey.org\/noticias\/programa-de-matem%C3%A1tica-en-salta\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/varkey.png\" title=\"Fundaci\u00f3n Varkey\" alt=\"Fundaci\u00f3n Varkey\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 180px!important\"><a class=\"ux-logo-link block image-\" title=\"The European Wergeland Centre\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/theewc.org\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/www.clayss.org\/wp-content\/uploads\/2023\/08\/weger.png\" title=\"The European Wergeland Centre\" alt=\"The European Wergeland Centre\" class=\"ux-logo-image block\" style=\"height:150px;\" \/><\/a><\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1694652130 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":349,"footnotes":""},"class_list":["post-2275","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Networks - CLAYSS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clayss.org\/en\/networks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Networks - CLAYSS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clayss.org\/en\/networks\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAYSS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T15:24:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clayss.org\\\/en\\\/networks\\\/\",\"url\":\"https:\\\/\\\/www.clayss.org\\\/en\\\/networks\\\/\",\"name\":\"Networks - CLAYSS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clayss.org\\\/#website\"},\"datePublished\":\"2023-07-26T13:02:31+00:00\",\"dateModified\":\"2025-06-19T15:24:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clayss.org\\\/en\\\/networks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clayss.org\\\/en\\\/networks\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clayss.org\\\/en\\\/networks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.clayss.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Networks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clayss.org\\\/#website\",\"url\":\"https:\\\/\\\/www.clayss.org\\\/\",\"name\":\"CLAYSS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clayss.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Networks - CLAYSS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clayss.org\/en\/networks\/","og_locale":"en_US","og_type":"article","og_title":"Networks - CLAYSS","og_url":"https:\/\/www.clayss.org\/en\/networks\/","og_site_name":"CLAYSS","article_modified_time":"2025-06-19T15:24:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clayss.org\/en\/networks\/","url":"https:\/\/www.clayss.org\/en\/networks\/","name":"Networks - CLAYSS","isPartOf":{"@id":"https:\/\/www.clayss.org\/#website"},"datePublished":"2023-07-26T13:02:31+00:00","dateModified":"2025-06-19T15:24:49+00:00","breadcrumb":{"@id":"https:\/\/www.clayss.org\/en\/networks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clayss.org\/en\/networks\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clayss.org\/en\/networks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clayss.org\/en\/"},{"@type":"ListItem","position":2,"name":"Networks"}]},{"@type":"WebSite","@id":"https:\/\/www.clayss.org\/#website","url":"https:\/\/www.clayss.org\/","name":"CLAYSS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clayss.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/pages\/2275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/comments?post=2275"}],"version-history":[{"count":14,"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/pages\/2275\/revisions"}],"predecessor-version":[{"id":6970,"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/pages\/2275\/revisions\/6970"}],"wp:attachment":[{"href":"https:\/\/www.clayss.org\/en\/wp-json\/wp\/v2\/media?parent=2275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}